{"id":159,"count":27,"description":"","link":"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/","name":"Duurzaam leven","slug":"duurzaam-leven","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nachhaltig leben | Bergfreunde Basislager<\/title>\n<meta name=\"description\" content=\"Eins vereint alle Bergfreunde: Die Liebe zur Natur. Um diese zu erhalten, wollen wir Tipps &amp; Tricks rund um einen nachhaltigen Lebensstil teilen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Duurzaam leven Archives\" \/>\n<meta property=\"og:description\" content=\"Eins vereint alle Bergfreunde: Die Liebe zur Natur. Um diese zu erhalten, wollen wir Tipps &amp; Tricks rund um einen nachhaltigen Lebensstil teilen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/\" \/>\n<meta property=\"og:site_name\" content=\"Bergfreunde\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/activiteiten\\\/duurzaam-leven\\\/\",\"url\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/activiteiten\\\/duurzaam-leven\\\/\",\"name\":\"Nachhaltig leben | Bergfreunde Basislager\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/#website\"},\"description\":\"Eins vereint alle Bergfreunde: Die Liebe zur Natur. Um diese zu erhalten, wollen wir Tipps & Tricks rund um einen nachhaltigen Lebensstil teilen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/activiteiten\\\/duurzaam-leven\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/activiteiten\\\/duurzaam-leven\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Duurzaam leven\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/\",\"name\":\"Bergfreunde\",\"description\":\"Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/#organization\",\"name\":\"Bergfreunde\",\"url\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Bergfreunde_DE_rgb.svg\",\"contentUrl\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Bergfreunde_DE_rgb.svg\",\"caption\":\"Bergfreunde\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bergfreunde.nl\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bergfreunde\",\"https:\\\/\\\/www.instagram.com\\\/bergfreundede\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nachhaltig leben | Bergfreunde Basislager","description":"Eins vereint alle Bergfreunde: Die Liebe zur Natur. Um diese zu erhalten, wollen wir Tipps & Tricks rund um einen nachhaltigen Lebensstil teilen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/","og_locale":"nl_NL","og_type":"article","og_title":"Duurzaam leven Archives","og_description":"Eins vereint alle Bergfreunde: Die Liebe zur Natur. Um diese zu erhalten, wollen wir Tipps & Tricks rund um einen nachhaltigen Lebensstil teilen!","og_url":"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/","og_site_name":"Bergfreunde","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/","url":"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/","name":"Nachhaltig leben | Bergfreunde Basislager","isPartOf":{"@id":"https:\/\/www.bergfreunde.nl\/blog\/#website"},"description":"Eins vereint alle Bergfreunde: Die Liebe zur Natur. Um diese zu erhalten, wollen wir Tipps & Tricks rund um einen nachhaltigen Lebensstil teilen!","breadcrumb":{"@id":"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bergfreunde.nl\/blog\/activiteiten\/duurzaam-leven\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.bergfreunde.nl\/blog\/"},{"@type":"ListItem","position":2,"name":"Duurzaam leven"}]},{"@type":"WebSite","@id":"https:\/\/www.bergfreunde.nl\/blog\/#website","url":"https:\/\/www.bergfreunde.nl\/blog\/","name":"Bergfreunde","description":"Blog","publisher":{"@id":"https:\/\/www.bergfreunde.nl\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bergfreunde.nl\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.bergfreunde.nl\/blog\/#organization","name":"Bergfreunde","url":"https:\/\/www.bergfreunde.nl\/blog\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bergfreunde.nl\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.bergfreunde.nl\/blog\/wp-content\/uploads\/2023\/12\/Bergfreunde_DE_rgb.svg","contentUrl":"https:\/\/www.bergfreunde.nl\/blog\/wp-content\/uploads\/2023\/12\/Bergfreunde_DE_rgb.svg","caption":"Bergfreunde"},"image":{"@id":"https:\/\/www.bergfreunde.nl\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bergfreunde","https:\/\/www.instagram.com\/bergfreundede\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.bergfreunde.nl\/blog\/wp-json\/wp\/v2\/tags\/159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bergfreunde.nl\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bergfreunde.nl\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bergfreunde.nl\/blog\/wp-json\/wp\/v2\/posts?tags=159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}